{"id":7961,"date":"2024-07-07T06:40:03","date_gmt":"2024-07-07T06:40:03","guid":{"rendered":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/"},"modified":"2024-07-07T06:40:10","modified_gmt":"2024-07-07T06:40:10","slug":"%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7","status":"publish","type":"product","link":"https:\/\/gostarpets.com\/ar\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/","title":{"rendered":"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + &#8211; MF MILANO Collar Nylon Brown 45&#215;2.2cm M+"},"content":{"rendered":"<p>\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + &#8211; MF MILANO Collar Nylon Brown 45&#215;2.2cm M+<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + &#8211; MF &#8230; <\/p>\n","protected":false},"featured_media":7962,"template":"","meta":{"inline_featured_image":false},"product_brand":[1046,1044,1045],"product_cat":[168,169,136],"product_tag":[172],"class_list":["post-7961","product","type-product","status-publish","has-post-thumbnail","product_brand-1046","product_brand-my-family","product_brand-my-family-2","product_cat-accessories","product_cat-collars","product_cat-dogs","product_tag-my-family","first","instock","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + - MF MILANO Collar Nylon Brown 45x2.2cm M+ - StarPets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gostarpets.com\/product\/\u0645\u0627\u064a-\u0641\u0627\u0645\u064a\u0644\u064a-\u0645\u064a\u0644\u0627\u0646-\u0637\u0648\u0642-\u0646\u064a\u0644\u0648\u0646-\u0628\u0646\u064a-45x2-2\u0633\u0645-\u0648\u0633\u0637\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + - MF MILANO Collar Nylon Brown 45x2.2cm M+ - StarPets\" \/>\n<meta property=\"og:description\" content=\"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + &#8211; MF ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gostarpets.com\/product\/\u0645\u0627\u064a-\u0641\u0627\u0645\u064a\u0644\u064a-\u0645\u064a\u0644\u0627\u0646-\u0637\u0648\u0642-\u0646\u064a\u0644\u0648\u0646-\u0628\u0646\u064a-45x2-2\u0633\u0645-\u0648\u0633\u0637\/\" \/>\n<meta property=\"og:site_name\" content=\"StarPets\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-07T06:40:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/\",\"url\":\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/\",\"name\":\"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + - MF MILANO Collar Nylon Brown 45x2.2cm M+ - StarPets\",\"isPartOf\":{\"@id\":\"https:\/\/gostarpets.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg\",\"datePublished\":\"2024-07-07T06:40:03+00:00\",\"dateModified\":\"2024-07-07T06:40:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#primaryimage\",\"url\":\"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg\",\"contentUrl\":\"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gostarpets.com\/ar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/gostarpets.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + &#8211; MF MILANO Collar Nylon Brown 45&#215;2.2cm M+\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gostarpets.com\/#website\",\"url\":\"https:\/\/gostarpets.com\/\",\"name\":\"StarPets\",\"description\":\"Pet care\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gostarpets.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + - MF MILANO Collar Nylon Brown 45x2.2cm M+ - StarPets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gostarpets.com\/product\/\u0645\u0627\u064a-\u0641\u0627\u0645\u064a\u0644\u064a-\u0645\u064a\u0644\u0627\u0646-\u0637\u0648\u0642-\u0646\u064a\u0644\u0648\u0646-\u0628\u0646\u064a-45x2-2\u0633\u0645-\u0648\u0633\u0637\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + - MF MILANO Collar Nylon Brown 45x2.2cm M+ - StarPets","og_description":"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + &#8211; MF ...","og_url":"https:\/\/gostarpets.com\/product\/\u0645\u0627\u064a-\u0641\u0627\u0645\u064a\u0644\u064a-\u0645\u064a\u0644\u0627\u0646-\u0637\u0648\u0642-\u0646\u064a\u0644\u0648\u0646-\u0628\u0646\u064a-45x2-2\u0633\u0645-\u0648\u0633\u0637\/","og_site_name":"StarPets","article_modified_time":"2024-07-07T06:40:10+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/","url":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/","name":"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + - MF MILANO Collar Nylon Brown 45x2.2cm M+ - StarPets","isPartOf":{"@id":"https:\/\/gostarpets.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#primaryimage"},"image":{"@id":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#primaryimage"},"thumbnailUrl":"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg","datePublished":"2024-07-07T06:40:03+00:00","dateModified":"2024-07-07T06:40:10+00:00","breadcrumb":{"@id":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#primaryimage","url":"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg","contentUrl":"https:\/\/gostarpets.com\/wp-content\/uploads\/2024\/07\/8058773275967.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/gostarpets.com\/product\/%d9%85%d8%a7%d9%8a-%d9%81%d8%a7%d9%85%d9%8a%d9%84%d9%8a-%d9%85%d9%8a%d9%84%d8%a7%d9%86-%d8%b7%d9%88%d9%82-%d9%86%d9%8a%d9%84%d9%88%d9%86-%d8%a8%d9%86%d9%8a-45x2-2%d8%b3%d9%85-%d9%88%d8%b3%d8%b7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gostarpets.com\/ar\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/gostarpets.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0645\u0627\u064a \u0641\u0627\u0645\u064a\u0644\u064a \u0645\u064a\u0644\u0627\u0646 \u0637\u0648\u0642 \u0646\u064a\u0644\u0648\u0646 \u0628\u0646\u064a 45\u00d72.2\u0633\u0645 \u0648\u0633\u0637 + &#8211; MF MILANO Collar Nylon Brown 45&#215;2.2cm M+"}]},{"@type":"WebSite","@id":"https:\/\/gostarpets.com\/#website","url":"https:\/\/gostarpets.com\/","name":"StarPets","description":"Pet care","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gostarpets.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/product\/7961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/media\/7962"}],"wp:attachment":[{"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/media?parent=7961"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/product_brand?post=7961"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/product_cat?post=7961"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gostarpets.com\/ar\/wp-json\/wp\/v2\/product_tag?post=7961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}